{"id":1334,"date":"2020-04-02T20:51:44","date_gmt":"2020-04-02T20:51:44","guid":{"rendered":"https:\/\/caesarluxurytravel.com\/viajar-depois-do-coronavirus\/"},"modified":"2020-04-02T21:00:47","modified_gmt":"2020-04-02T21:00:47","slug":"viajar-depois-do-coronavirus","status":"publish","type":"post","link":"https:\/\/caesarluxurytravel.com\/pt-br\/viajar-depois-do-coronavirus\/","title":{"rendered":"VIAJAR DEPOIS DO CORONAVIRUS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><p>O mundo inteiro est\u00e1 passando por uma das \u00e9pocas mais complicadas da era moderna, uma pandemia que coloca a estrutura da nossa sociedade em s\u00e9rias e profundas dificuldades. Todos os setores est\u00e3o passando por grandes mudan\u00e7as, da sa\u00fade \u00e1s industrias, para n\u00e3o falar do turismo. Entre as poucas certezas que o <strong>coronav\u00edrus<\/strong> nos d\u00e1, \u00e9 saber que tudo isso uma dia vaichegar ao fim. \u00c9 a hist\u00f3ria do homem, que sempre foi capaz de resistir, se adaptar e evoluir mesmo em situa\u00e7\u00f5es muito mais graves. Outra coisa certa \u00e9 que nossas vidas ainda sofrer\u00e3o um choque, talvez sejam apenas pequenos detalhes, mas o dia a dia que redescobriremos (em breve, espero!), nunca ser\u00e1 o mesmo de algumas semanas atr\u00e1s.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>Neste artigo, queremos analisar o que significar\u00e1 <strong>viajar para a It\u00e1lia depois do coronav\u00edrus<\/strong>: nos faremos perguntas \u00e0s quais tentaremos responder, hipotetizaremos uns cen\u00e1rios e proporemos novas id\u00e9ias e atitudes \u00e0 viagem.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>A premissa \u00f3bvia mas necess\u00e1ria, \u00e9 que tudo o que voc\u00ea l\u00ea reflete apenas nosso ponto de vista. N\u00e3o tem base cient\u00edfica: \u00e9 simplesmente uma imagem de como imaginamos <strong>o futuro das viagens<\/strong>.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">QUAIS S\u00c3O AS FASES PSICOL\u00d3GICAS QUE VAMOS PASSAR EM RELA\u00c7\u00c3O \u00c0 VIAGEM?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Medo: \u00e9 normal que neste momento ningu\u00e9m esteja realmente pensando em viajar. O medo significa sensatez, dado que novos surtos come\u00e7am continuamente em todos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incerteza: quando a situa\u00e7\u00e3o vai parecer sob controle, come\u00e7aremos a sonhar em viajar. Ser\u00e1 a nossa for\u00e7a vital. No entanto, tentaremos descobrir quais s\u00e3o as \u00e1reas seguras, os riscos que ainda existem e as limita\u00e7\u00f5es. Digamos que, com incerteza, uma fase de recupera\u00e7\u00e3o vai come\u00e7ar, mas o amanh\u00e3 ainda n\u00e3o est\u00e1 claro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuidado: o cen\u00e1rio agora ser\u00e1 cada dia mais control\u00e1vel, o v\u00edrus quase completamente derrotado, talvez estaremos pr\u00f3ximos de uma vacina. Viajar \u00e9 um pensamento ainda mais concreto, mas a cautela ser\u00e1 justamente um freio por mais algum tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recupera\u00e7\u00e3o: a viagem est\u00e1 enraizada em n\u00f3s desde os tempos antigos, somos incapazes de parar nosso desejo de descoberta. Agora podemos finalmente voltar a explorar o mundo, a It\u00e1lia s\u00f3 pode estar no topo da lista! \u00c9 poss\u00edvel e desej\u00e1vel que o setor de viagens, o primeiro a ser severamente afetado pela pandemia, reinicie com for\u00e7a quando as condi\u00e7\u00f5es permitirem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>QUANDO SER\u00c1 POSS\u00cdVEL VIAJAR DE NOVO PARA IT\u00c1LIA?<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>Dif\u00edcil de fazer previs\u00f5es: \u00e9 claro que ningu\u00e9m ainda tem como responder. No entanto, podemos dizer que a It\u00e1lia foi a primeira na\u00e7\u00e3o a sofrer cont\u00e1gio em larga escala depois da China , por isso implementou medidas de controle e preven\u00e7\u00e3o desde os primeiros dias de mar\u00e7o. Como resultado, ser\u00e1 um dos primeiros pa\u00edses a emergir da crise. O decreto restritivo existente \u00e9 v\u00e1lido at\u00e9 a metade de abril, o pensamento comum \u00e9 que ser\u00e1 prorrogado por todo o m\u00eas. Se os progressos dos \u00faltimos dias continuarem, maio ser\u00e1 o m\u00eas em que a vida &#8220;normal&#8221; ser\u00e1 gradualmente retomada. Indicamos a temporada de ver\u00e3o (mais julho do que junho) como um <strong>novo come\u00e7o das viagens na It\u00e1lia<\/strong>.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">QUAIS AS PRINCIPAIS MUDAN\u00c7AS DEPOIS DO CORONAVIRUS?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Controles no aeroporto: \u00e9 claro que, quando pudermos voltar a viagem, teremos que passar por maiores controles de sa\u00fade no aeroporto. Em fim, isso n\u00e3o ser\u00e1 um problema; de fato, ser\u00e1 \u00fatil. O \u00fanico pequeno inc\u00f3modo \u00e9 que ficaremos mais tempo na fila.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Companhias a\u00e9reas: est\u00e3o entre as empresas mais afetadas pelo coronav\u00edrus. Neste momento, o tr\u00e1fego a\u00e9reo \u00e9 quase zero e, com certeza, essas semanas deixar\u00e3o uma ferida aberta. Alguns v\u00e3o falir, umas novas surgir\u00e3o, mudando radicalmente o m\u00e9todo e a comunica\u00e7\u00e3o com os clientes. Ser\u00e1 algo novo a ser e descoberto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">OTA: Como as companhias a\u00e9reas, Booking, Expedia e outras empresas de viagens on-line (OTAs) tamb\u00e9m est\u00e3o sofrendo enormes danos. Antes da pandemia, eles eram os l\u00edderes do setor de turismo, controlando a comunica\u00e7\u00e3o, as regras at\u00e9 os desejos dos consumidores. O coronav\u00edrus pode perturbar este mundo, as OTAs podem entrar em colapso, incentivando o desenvolvimento de novas formas de pesquisa e reserva de estadias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comunica\u00e7\u00e3o e ofertas de hot\u00e9is: o mundo dos hot\u00e9is, at\u00e9 agora &#8220;escravos&#8221; das pol\u00edticas impostas pelos gigantes, est\u00e1 automaticamente ligado \u00e0 crise dos OTA. Para eles, \u00e9 uma grande oportunidade de desintermediar, abordando diretamente o consumidor final. N\u00e3o ser\u00e1 f\u00e1cil, vivemos em um mundo que se move em grande velocidade: os hot\u00e9is ter\u00e3o de encontrar maneiras r\u00e1pidas, cativantes e f\u00e1ceis de usar para acostumar os viajantes a n\u00e3o recorrer aos OTAs, economizando milh\u00f5es de euros em comiss\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">QUAIS SER\u00c3O OS PROBLEMES?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o consumidor final, o principal problema ser\u00e1 a confus\u00e3o. Se o mundo das viagens realmente sofrer mudan\u00e7as profundas, haver\u00e1 um caos no come\u00e7o. Milhares de ofertas, propostas e novas formas de fazer; poder\u00edamos nos encontrar em um labirinto do qual \u00e9 dif\u00edcil achar o que est\u00e1vamos procurando. At\u00e9 hoje o processo era simples e consolidado: site para compra de v\u00f4os, OTA para escolher hot\u00e9is e experi\u00eancias para fazer. Para os menos pr\u00e1ticos ou mais exigentes, havia a ag\u00eancia de viagens que cuidava de tudo. Esses procedimentos podem mudar radicalmente ou at\u00e9 desaparecer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">QUAIS SER\u00c3O OS BENEF\u00cdCIOS?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois de uma crise, sempre tem uma recupera\u00e7\u00e3o. Grandes oportunidades s\u00e3o criadas, aqueles que aproveitar\u00e3o o momento certo, ditar\u00e3o as regras da viagem nos pr\u00f3ximos anos. Para o consumidor final, isso se traduz potencialmente em uma variedade maior de ofertas, novas propostas interessantes, pol\u00edticas mais flex\u00edveis e personalizadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p><strong>COMO \u00c8 QUE UM DESIGNER DE VIAGENS PODE AJUDAR?<\/strong><\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>Essencialmente, um designer de viagens \u00e9 aquele que cuida de evitar os problemas e explorar as vantagens. Nosso trabalho se desenvolve em v\u00e1rias fases: come\u00e7amos com consultas durante as quais nos conhecemos e come\u00e7amos com as bases da viagem, avaliando fatores importantes como per\u00edodo, dura\u00e7\u00e3o e or\u00e7amento. Passamos ent\u00e3o \u00e0 elabora\u00e7\u00e3o de alguns <strong>roteiros adaptados aos desejos do cliente<\/strong>, a <strong>It\u00e1lia<\/strong> \u00e9 t\u00e3o cheia de maravilhas que a programa\u00e7\u00e3o correta \u00e9 essencial para viv\u00ea-las ao m\u00e1ximo. Em seguida, cuidamos das reservas de <strong>hot\u00e9is<\/strong>, <strong>transporte<\/strong> e <strong>experi\u00eancias<\/strong>, realizando pesquisas aprofundadas e aproveitando o relacionamento consolidado com outros parceiros. Por fim, ajudamos o cliente em todos os aspectos, mesmo durante a viagem.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p><strong>POR QUE PLANEJAR UMA VIAGEM NA IT\u00c1LIA AGORA?<\/strong><\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>Atualmente, os pre\u00e7os dos voos e hot\u00e9is certamente ficar\u00e3o mais baixos e j\u00e1 pararam em compara\u00e7\u00e3o com a tend\u00eancia normal. \u00c9 o momento de aproveitar a oportunidade de planejar uma <strong>viagem na It\u00e1lia<\/strong> para o ver\u00e3o de 2020, para o outono de 2020 ou mesmo para a temporada de <strong>2021<\/strong>. Basicamente, n\u00e3o h\u00e1 nada a perder, pois tudo pode ser cancelado sem pagar um centavo at\u00e9 alguns dias antes o in\u00edcio da viagem. Entre em contato conosco e conversaremos sobre isso de acordo com suas necessidades.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"O mundo inteiro est\u00e1 passando por uma das \u00e9pocas mais complicadas da era moderna, uma pandemia que coloca a estrutura da nossa sociedade em s\u00e9rias e profundas dificuldades. Todos os setores est\u00e3o passando por grandes mudan\u00e7as, da sa\u00fade \u00e1s industrias, para n\u00e3o falar do turismo. Entre as poucas certezas que o coronav\u00edrus nos d\u00e1, \u00e9&#8230; <a class=\"view-article\" href=\"https:\/\/caesarluxurytravel.com\/pt-br\/viajar-depois-do-coronavirus\/\">View Article<\/a>","protected":false},"author":3,"featured_media":1328,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[276,270,281,271,283,139],"class_list":["post-1334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias-italianas","tag-coronavirus","tag-dicas-de-viagem","tag-travel-designers","tag-viagem-na-italia","tag-viagem-na-italia-2021","tag-viagens"],"_links":{"self":[{"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/posts\/1334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/comments?post=1334"}],"version-history":[{"count":2,"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/posts\/1334\/revisions"}],"predecessor-version":[{"id":1338,"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/posts\/1334\/revisions\/1338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/media\/1328"}],"wp:attachment":[{"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/pt-br\/wp-json\/wp\/v2\/tags?post=1334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}