{"id":1336,"date":"2020-04-02T20:59:59","date_gmt":"2020-04-02T20:59:59","guid":{"rendered":"https:\/\/caesarluxurytravel.com\/viajar-despues-del-coronavirus\/"},"modified":"2020-04-02T21:01:21","modified_gmt":"2020-04-02T21:01:21","slug":"viajar-despues-del-coronavirus","status":"publish","type":"post","link":"https:\/\/caesarluxurytravel.com\/es\/viajar-despues-del-coronavirus\/","title":{"rendered":"VIAJAR DESPUES DEL CORONAVIRUS"},"content":{"rendered":"\n<p><p>El mundo entero est\u00e1 atravesando uno de los per\u00edodos m\u00e1s complicados de la era moderna, una pandemia que pone la estructura de nuestra sociedad en serias y profundas dificultades. Todos los sectores est\u00e1n experimentando cambios importantes, desde la atenci\u00f3n m\u00e9dica hasta las industrias, obviamente, hasta el turismo. Entre las pocas certezas que nos da el <strong>coronavirus<\/strong>, existe la conciencia de que todo esto est\u00e1 de tr\u00e1nsito. Es la historia del ser humano, que siempre ha sido capaz de resistir, adaptarse y evolucionar incluso en situaciones mucho m\u00e1s graves. Otra cosa clara es que nuestras vidas seguir\u00e1n sufriendo un shock, tal vez ser\u00e1n solo peque\u00f1os detalles, pero la vida cotidiana que redescubriremos (\u00a1pronto, con suerte!) Nunca ser\u00e1 la misma que hace unas semanas.<\/p><\/p>\n\n\n\n<p><p>En este art\u00edculo queremos analizar qu\u00e9 significa <strong>viajar a Italia<\/strong> <strong>despu\u00e9s del coronavirus<\/strong>: nos haremos preguntas a las que intentaremos responder, plantearemos hip\u00f3tesis sobre algunos escenarios y propondremos nuevas ideas y enfoques de viaje.<\/p><\/p>\n\n\n\n<p><p>La premisa obvia pero necesaria es que todo lo que lees refleja solo nuestro punto de vista. No hay una base cient\u00edfica, es simplemente una imagen de c\u00f3mo imaginamos el <strong>futuro de los viajes<\/strong>.<\/p><\/p>\n\n\n\n<p>\u00bfCU\u00c1LES SER\u00c1N LAS FASES PSICOL\u00d3GICAS POR LAS QUE PASAREMOS EN RELACI\u00d3N A LOS VIAJES?<\/p>\n\n\n\n<p>Miedo: es normal que nadie est\u00e9 pensando en viajar en este momento. El miedo rima sabiamente, ya que continuamente ocurren nuevos brotes en varios pa\u00edses.<\/p>\n\n\n\n<p>Incertidumbre: cuando la situaci\u00f3n parece estar bajo control, comenzaremos a so\u00f1ar con viajar, ser\u00e1 nuestra sangre vital. Sin embargo, miraremos a nuestro alrededor para descubrir cu\u00e1les son las \u00e1reas seguras, los riesgos que a\u00fan existen y las limitaciones. Digamos que con la incertidumbre comienza una fase de recuperaci\u00f3n, pero el futuro a\u00fan no est\u00e1 claro.<\/p>\n\n\n\n<p>Precauci\u00f3n: el escenario ahora es cada vez m\u00e1s manejable, el virus est\u00e1 casi completamente derrotado, tal vez estamos cerca de una vacuna. Viajar es un pensamiento concreto, pero la precauci\u00f3n ser\u00e1 un freno por un tiempo m\u00e1s.<\/p>\n\n\n\n<p>Recuperaci\u00f3n: el viaje est\u00e1 arraigado en nosotros desde la antig\u00fcedad, no podemos frenar nuestro deseo de descubrimiento. Ahora finalmente podemos volver a explorar el mundo, \u00a1Italia solo puede estar en la parte superior de la lista! Es posible y deseable que el sector de viajes, el primero en verse gravemente afectado por la pandemia, comience de nuevo tan pronto como las condiciones lo permitan.<\/p>\n\n\n\n<p><p><strong>\u00bf<\/strong><strong>CU\u00c1NDO SER\u00c1 POSIBLE HACER NUOEVAMENTE UN<\/strong> <strong>VIAJE A ITALIA<\/strong>?<\/p><\/p>\n\n\n\n<p><p>Dif\u00edcil predicir, est\u00e1 claro que nadie tiene a\u00fan los medios para hacerlo. Sin embargo, podemos decir que Italia fue la primera naci\u00f3n en sufrir un contagio a gran escala despu\u00e9s de China, por lo que implement\u00f3 medidas de control y prevenci\u00f3n desde los primeros d\u00edas de marzo. Como resultado, ser\u00e1 uno de los primeros pa\u00edses en salir de la crisis. El decreto restrictivo existente es v\u00e1lido hasta el 13 de abril, el pensamiento com\u00fan es que se extender\u00e1 por todo el mes. Si el progreso de los \u00faltimos d\u00edas contin\u00faa, mayo ser\u00e1 el mes en el que la vida \u00abnormal\u00bb se reanudar\u00e1 gradualmente. Indicamos la temporada de verano (m\u00e1s julio que junio) como un <strong>nuevo comienzo para viajar en Italia.<\/strong><\/p><\/p>\n\n\n\n<p>\u00bfCU\u00c1LES SER\u00c1N LOS CAMBIOS PRINCIPALES EN COMPARACI\u00d3N CON LOS ENFOQUES PRE CORONAVIRUS?<\/p>\n\n\n\n<p>Controles en el aeropuerto: es seguro que cuando podamos reanudar el viaje, estaremos sujetos a mayores controles de salud en el aeropuerto. Al final, esto no ser\u00e1 un problema, de hecho, ser\u00e1 \u00fatil. El \u00fanico punto d\u00e9bil es que haremos m\u00e1s colas.<\/p>\n\n\n\n<p>Aerol\u00edneas: se encuentran entre las empresas m\u00e1s afectadas por el coronavirus. En este momento el tr\u00e1fico a\u00e9reo es casi cero y con seguridad estas semanas dejar\u00e1n una herida abierta. Algunos fracasar\u00e1n, surgir\u00e1n nuevos, cambiar\u00e1n radicalmente el enfoque y la comunicaci\u00f3n con los clientes. Ser\u00e1 un campo para ser entendido y descubierto.<\/p>\n\n\n\n<p>OTA: Al igual que las aerol\u00edneas, Booking, Expedia y otras OTA (online travel agencies) tambi\u00e9n est\u00e1n sufriendo da\u00f1os enormes. Antes de la pandemia, eran los l\u00edderes del sector tur\u00edstico, controlando la comunicaci\u00f3n, el enfoque, las normas e incluso los deseos de los consumidores. El coronavirus podr\u00eda alterar este mundo, las OTA podr\u00edan colapsar y favorecer el desarrollo de nuevas formas de b\u00fasqueda y reserva.<\/p>\n\n\n\n<p>Comunicaci\u00f3n y ofertas de hoteles: el mundo de los hoteles, hasta ahora \u00abesclavos\u00bb de las pol\u00edticas impuestas por los gigantes, se vincula autom\u00e1ticamente con la crisis de la OTA. Para ellos es una gran oportunidad para desintermediarse dirigi\u00e9ndose directamente al consumidor final. No ser\u00e1 f\u00e1cil, vivimos en un mundo que se mueve a gran velocidad: los hoteles tendr\u00e1n que encontrar formas r\u00e1pidas, cautivadoras y f\u00e1ciles de usar para que los viajeros se acostumbren a no recurrir a las OTA, ahorrando millones de euros en comisiones.<\/p>\n\n\n\n<p>\u00bfCUALES SER\u00c1N LAS TRAMPAS?<\/p>\n\n\n\n<p>Para el consumidor final, el principal obst\u00e1culo ser\u00e1 la confusi\u00f3n. Si el mundo de los viajes realmente experimenta cambios profundos, al principio habr\u00e1 caos. Miles de ofertas, propuestas y nuevas formas de hacer; podr\u00edamos encontrarnos en un laberinto del que es dif\u00edcil salir con lo que est\u00e1bamos buscando. Hasta hoy, el proceso era simple y consolidado: p\u00e1gina web para comprar vuelos y OTA para elegir hoteles y experiencias. Para los menos pr\u00e1cticos o m\u00e1s exigentes estaba la agencia de viajes que se encargaba de todo. Estos procedimientos podr\u00edan cambiar radicalmente o incluso desaparecer.<\/p>\n\n\n\n<p>\u00bfCU\u00c1LES SER\u00c1N LOS BENEFICIOS?<\/p>\n\n\n\n<p>Despu\u00e9s de una crisis siempre hay una recuperaci\u00f3n. Se crean grandes oportunidades, quienes aprovechar\u00e1n la oportunidad en el momento adecuado, dictar\u00e1n las reglas de viaje en los pr\u00f3ximos a\u00f1os. Para el consumidor final, esto se traduce potencialmente en una mayor variedad de ofertas, nuevas interesantes propuestas, pol\u00edticas m\u00e1s flexibles y personalizadas.<\/p>\n\n\n\n<p><p><strong>\u00bfC\u00d3MO TE PUEDE AYUDAR UN TRAVEL DESIGNER?<\/strong><\/p><\/p>\n\n\n\n<p><p>Esencialmente, un travel designer es el que se encarga de esquivar las trampas y explotar las ventajas. Nuestro trabajo se desarrolla en varias fases: comenzamos con entrevistas durante las cuales nos conocemos y comenzamos a sentar las bases del viaje, evaluando factores importantes como el per\u00edodo, la duraci\u00f3n y el presupuesto. Luego pasamos a la redacci\u00f3n de algunos <strong>itinerarios confeccionados en base a los deseos del cliente<\/strong>, Italia est\u00e1 tan llena de maravillas que la programaci\u00f3n correcta es esencial para vivirlas al m\u00e1ximo. Luego nos ocupamos de las <strong>reservas de hoteles, transportes y experiencias<\/strong>, investigamos en profundidad y aprovechamos las relaciones consolidadas con otros socios. Finalmente, ayudamos al cliente en todos los aspectos, incluso durante el viaje.<\/p><\/p>\n\n\n\n<p><p><strong>\u00bfPOR QU\u00c9 PLANIFICAR UN VIAJE A ITALIA AHORA? <\/strong><\/p><\/p>\n\n\n\n<p><p>Hoy en d\u00eda, los precios de los vuelos y hoteles ciertamente han bajado o al menos se han detenido en comparaci\u00f3n con la tendencia cl\u00e1sica. Es el momento de aprovechar para <strong>planificar un viaje a Italia<\/strong> para el fin de verano u oto\u00f1o de <strong>2020<\/strong> y para la temporada <strong>2021<\/strong>. B\u00e1sicamente <strong>no hay nada que perder<\/strong>, ya que todo se puede cancelar sin pagar un centavo hasta pocos d\u00edas desde el inicio del viaje. Cont\u00e1ctanos y hablaremos juntos de acuerdo a tus necesidades.<\/p><\/p>\n<noscript class=\"ninja-forms-noscript-message\">\n\tAviso: Se requiere JavaScript para este contenido.<\/noscript>\n<div id=\"nf-form-8-cont\" class=\"nf-form-cont\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-8\" aria-describedby=\"nf-form-errors-8\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- That data is being printed as a workaround to page builders reordering the order of the scripts loaded-->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='8';form.settings={\"objectType\":\"Form Setting\",\"editActive\":true,\"title\":\"Contatto da sito ESP\",\"created_at\":\"2018-10-15 17:02:51\",\"form_title\":\"Form ENG - Copia\",\"default_label_pos\":\"above\",\"show_title\":\"0\",\"clear_complete\":\"1\",\"hide_complete\":\"1\",\"logged_in\":\"0\",\"wrapper_class\":\"\",\"element_class\":\"\",\"key\":\"\",\"add_submit\":\"0\",\"changeEmailErrorMsg\":\"Introduce una direcci\\u00f3n de correo electr\\u00f3nico v\\u00e1lida.\",\"changeDateErrorMsg\":\"\\u00a1Introduce una fecha v\\u00e1lida!\",\"confirmFieldErrorMsg\":\"Estos campos deben coincidir.\",\"fieldNumberNumMinError\":\"Error de n\\u00famero m\\u00ednimo\",\"fieldNumberNumMaxError\":\"Error de n\\u00famero m\\u00e1ximo\",\"fieldNumberIncrementBy\":\"Increm\\u00e9ntalo por \",\"formErrorsCorrectErrors\":\"Corrige los errores antes de enviar este formulario.\",\"validateRequiredField\":\"Esto es un campo obligatorio.\",\"honeypotHoneypotError\":\"Error de Honeypot\",\"fieldsMarkedRequired\":\"Los campos marcados con <span class=\\\"ninja-forms-req-symbol\\\">*<\\\/span> son obligatorios\",\"currency\":\"\",\"unique_field_error\":\"A form with this value has already been submitted.\",\"not_logged_in_msg\":\"\",\"sub_limit_msg\":\"The form has reached its submission limit.\",\"calculations\":[],\"formContentData\":[\"nombre_1539615857322\",\"apellido_1539616135471\",\"correo_electronico_1539616208433\",\"telefono_1539616166363\",\"ciudad_1539616177186\",\"pais_1539616189482\",\"codigo_postal_1539616201483\",\"mensaje_1539617317414\",\"autorizo_el_tratamiento_de_los_datos_personales_reg_2016_679_ue_1551876833155\",\"quiero_recibir_informaciones_comerciales_1539616254152\",\"enviar_1539616282718\"],\"drawerDisabled\":false,\"allow_public_link\":0,\"embed_form\":\"\",\"repeatable_fieldsets\":\"\",\"ninjaForms\":\"Ninja Forms\",\"fieldTextareaRTEInsertLink\":\"Insertar enlace\",\"fieldTextareaRTEInsertMedia\":\"Insertar medios\",\"fieldTextareaRTESelectAFile\":\"Seleccione un archivo\",\"tableInsertRowAbove\":\"Insert Row Above\",\"tableInsertRowBelow\":\"Insert Row Below\",\"tableInsertColumnLeft\":\"Insert Column Left\",\"tableInsertColumnRight\":\"Insert Column Right\",\"tableDeleteRow\":\"Delete Row\",\"tableDeleteColumn\":\"Delete Column\",\"tableDeleteTable\":\"Delete Table\",\"tableLegacyNotice\":\"This content has tables in the old editor format. Custom styles are preserved until converted. Editing will update to the new format.\",\"tableLegacyConvert\":\"Convert Now\",\"tableInsertTable\":\"Insert Table\",\"dismiss\":\"Descartar\",\"insertLink\":\"Insertar enlace\",\"formHoneypot\":\"Si eres un ser humano y est\\u00e1s viendo este campo, por favor d\\u00e9jalo vac\\u00edo.\",\"fileUploadOldCodeFileUploadInProgress\":\"Subida de archivo en curso.\",\"fileUploadOldCodeFileUpload\":\"SUBIDA DE ARCHIVO\",\"currencySymbol\":\"&#36;\",\"thousands_sep\":\".\",\"decimal_point\":\",\",\"siteLocale\":\"es_ES\",\"dateFormat\":\"d\\\/m\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"de\",\"previousMonth\":\"Mes anterior\",\"nextMonth\":\"Pr\\u00f3ximo mes\",\"months\":[\"Enero\",\"Febrero\",\"Marzo\",\"Abril\",\"Mayo\",\"Junio\",\"Julio\",\"Agosto\",\"Septiembre\",\"Octubre\",\"Noviembre\",\"Diciembre\"],\"monthsShort\":[\"Ene\",\"Feb\",\"Mar\",\"Abr\",\"Mayo\",\"Jun\",\"Jul\",\"Ago\",\"Sep\",\"Oct\",\"Nov\",\"Dic\"],\"weekdays\":[\"Domingo\",\"Lunes\",\"Martes\",\"Mi\\u00e9rcoles\",\"Jueves\",\"Viernes\",\"S\\u00e1bado\"],\"weekdaysShort\":[\"Dom\",\"Lun\",\"Mar\",\"Mi\\u00e9\",\"Jue\",\"Vie\",\"S\\u00e1b\"],\"weekdaysMin\":[\"Do\",\"Lu\",\"Ma\",\"Mi\",\"Ju\",\"Vi\",\"S\\u00e1\"],\"recaptchaConsentMissing\":\"reCaptcha validation couldn&#039;t load.\",\"recaptchaMissingCookie\":\"reCaptcha v3 validation couldn&#039;t load the cookie needed to submit the form.\",\"recaptchaConsentEvent\":\"Accept reCaptcha cookies before sending the form.\",\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":1,\"idAttribute\":\"id\",\"type\":\"firstname\",\"label\":\"Nombre\",\"key\":\"nombre_1539615857322\",\"label_pos\":\"above\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"au-col au-col-2\",\"element_class\":\"au-ninjaforms-element\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"fname\",\"personally_identifiable\":1,\"drawerDisabled\":\"\",\"value\":\"\",\"id\":58,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"firstname\",\"element_templates\":[\"firstname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":2,\"idAttribute\":\"id\",\"label\":\"Apellido\",\"type\":\"lastname\",\"key\":\"apellido_1539616135471\",\"label_pos\":\"above\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"au-col au-col-2\",\"element_class\":\"au-ninjaforms-element\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"lname\",\"personally_identifiable\":1,\"value\":\"\",\"id\":59,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"lastname\",\"element_templates\":[\"lastname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":3,\"idAttribute\":\"id\",\"label\":\"Correo Electr\\u00f3nico\",\"type\":\"email\",\"key\":\"correo_electronico_1539616208433\",\"label_pos\":\"above\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"au-ninjaforms-element\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"email\",\"personally_identifiable\":1,\"value\":\"\",\"id\":60,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"email\",\"element_templates\":[\"email\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":4,\"idAttribute\":\"id\",\"label\":\"Tel\\u00e9fono\",\"type\":\"phone\",\"key\":\"telefono_1539616166363\",\"label_pos\":\"above\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"au-ninjaforms-element\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caratteri rimasti\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"phone\",\"personally_identifiable\":1,\"value\":\"\",\"id\":61,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"tel\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":5,\"idAttribute\":\"id\",\"label\":\"Ciudad\",\"type\":\"city\",\"key\":\"ciudad_1539616177186\",\"label_pos\":\"above\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"au-ninjaforms-element\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caratteri rimasti\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"city\",\"personally_identifiable\":\"\",\"value\":\"\",\"id\":62,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"city\",\"element_templates\":[\"city\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":6,\"idAttribute\":\"id\",\"label\":\"Pa\\u00eds\",\"type\":\"listcountry\",\"key\":\"pais_1539616189482\",\"label_pos\":\"above\",\"required\":\"\",\"options\":[{\"label\":\"- Elige el pa\\u00eds -\",\"value\":\"\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Afganist\\u00e1n \",\"value\":\"AF\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Aland Islands\",\"value\":\"AX\",\"calc\":\"\",\"selected\":0,\"order\":2},{\"label\":\"Albania \",\"value\":\"AL\",\"calc\":\"\",\"selected\":0,\"order\":3},{\"label\":\"Alemania\",\"value\":\"DE\",\"calc\":\"\",\"selected\":0,\"order\":87},{\"label\":\"Andorra \",\"value\":\"AD\",\"calc\":\"\",\"selected\":0,\"order\":6},{\"label\":\"Angola \",\"value\":\"AO\",\"calc\":\"\",\"selected\":0,\"order\":7},{\"label\":\"Anguila\",\"value\":\"AI\",\"calc\":\"\",\"selected\":0,\"order\":8},{\"label\":\"Antigua y Barbuda \",\"value\":\"AG\",\"calc\":\"\",\"selected\":0,\"order\":10},{\"label\":\"Antillas Holandesas \",\"value\":\"AN\",\"calc\":\"\",\"selected\":0,\"order\":161},{\"label\":\"Ant\\u00e1rtida \",\"value\":\"AQ\",\"calc\":\"\",\"selected\":0,\"order\":9},{\"label\":\"Arabia Saudita \",\"value\":\"SA\",\"calc\":\"\",\"selected\":0,\"order\":200},{\"label\":\"Argelia\",\"value\":\"DZ\",\"calc\":\"\",\"selected\":0,\"order\":4},{\"label\":\"Argentina \",\"value\":\"AR\",\"calc\":\"\",\"selected\":1,\"order\":11},{\"label\":\"Armenia \",\"value\":\"AM\",\"calc\":\"\",\"selected\":0,\"order\":12},{\"label\":\"Aruba\",\"value\":\"AW\",\"calc\":\"\",\"selected\":0,\"order\":13},{\"label\":\"Australia \",\"value\":\"AU\",\"calc\":\"\",\"selected\":0,\"order\":14},{\"label\":\"Austria\",\"value\":\"AT\",\"calc\":\"\",\"selected\":0,\"order\":15},{\"label\":\"Azerbaiy\\u00e1n \",\"value\":\"AZ\",\"calc\":\"\",\"selected\":0,\"order\":16},{\"label\":\"Bahamas\",\"value\":\"BS\",\"calc\":\"\",\"selected\":0,\"order\":17},{\"label\":\"Bahrein \",\"value\":\"BH\",\"calc\":\"\",\"selected\":0,\"order\":18},{\"label\":\"Bangladesh\",\"value\":\"BD\",\"calc\":\"\",\"selected\":0,\"order\":19},{\"label\":\"Barbados\",\"value\":\"BB\",\"calc\":\"\",\"selected\":0,\"order\":20},{\"label\":\"Belar\\u00fas \",\"value\":\"BY\",\"calc\":\"\",\"selected\":0,\"order\":21},{\"label\":\"Belice\",\"value\":\"BZ\",\"calc\":\"\",\"selected\":0,\"order\":23},{\"label\":\"Benin\",\"value\":\"BJ\",\"calc\":\"\",\"selected\":0,\"order\":24},{\"label\":\"Bermudas\",\"value\":\"BM\",\"calc\":\"\",\"selected\":0,\"order\":25},{\"label\":\"Bolivia\",\"value\":\"BO\",\"calc\":\"\",\"selected\":0,\"order\":27},{\"label\":\"Bonaire, Sint Eustatius and Saba\",\"value\":\"BQ\",\"calc\":\"\",\"selected\":0,\"order\":28},{\"label\":\"Bosnia and Herzegowina\",\"value\":\"BA\",\"calc\":\"\",\"selected\":0,\"order\":29},{\"label\":\"Botswana\",\"value\":\"BW\",\"calc\":\"\",\"selected\":0,\"order\":30},{\"label\":\"Brasil\",\"value\":\"BR\",\"calc\":\"\",\"selected\":0,\"order\":32},{\"label\":\"Brunei Darussalam\",\"value\":\"BN\",\"calc\":\"\",\"selected\":0,\"order\":34},{\"label\":\"Bulgaria\",\"value\":\"BG\",\"calc\":\"\",\"selected\":0,\"order\":35},{\"label\":\"Burkina Faso\",\"value\":\"BF\",\"calc\":\"\",\"selected\":0,\"order\":36},{\"label\":\"Burundi\",\"value\":\"BI\",\"calc\":\"\",\"selected\":0,\"order\":37},{\"label\":\"But\\u00e1n \",\"value\":\"BT\",\"calc\":\"\",\"selected\":0,\"order\":26},{\"label\":\"B\\u00e9lgica \",\"value\":\"BE\",\"calc\":\"\",\"selected\":0,\"order\":22},{\"label\":\"Cabo Verde\",\"value\":\"CV\",\"calc\":\"\",\"selected\":0,\"order\":38},{\"label\":\"Camboya \",\"value\":\"KH\",\"calc\":\"\",\"selected\":0,\"order\":39},{\"label\":\"Camer\\u00fan \",\"value\":\"CM\",\"calc\":\"\",\"selected\":0,\"order\":40},{\"label\":\"Canad\\u00e1 \",\"value\":\"CA\",\"calc\":\"\",\"selected\":0,\"order\":41},{\"label\":\"Chad\",\"value\":\"TD\",\"calc\":\"\",\"selected\":0,\"order\":44},{\"label\":\"Chile\",\"value\":\"CL\",\"calc\":\"\",\"selected\":0,\"order\":45},{\"label\":\"China\",\"value\":\"CN\",\"calc\":\"\",\"selected\":0,\"order\":46},{\"label\":\"Chipre\",\"value\":\"CY\",\"calc\":\"\",\"selected\":0,\"order\":59},{\"label\":\"Colombia\",\"value\":\"CO\",\"calc\":\"\",\"selected\":0,\"order\":49},{\"label\":\"Comoras\",\"value\":\"KM\",\"calc\":\"\",\"selected\":0,\"order\":50},{\"label\":\"Congo\",\"value\":\"CG\",\"calc\":\"\",\"selected\":0,\"order\":51},{\"label\":\"Costa de Marfil \",\"value\":\"CI\",\"calc\":\"\",\"selected\":0,\"order\":55},{\"label\":\"Costa Rica\",\"value\":\"CR\",\"calc\":\"\",\"selected\":0,\"order\":54},{\"label\":\"Croatia\",\"value\":\"HR\",\"calc\":\"\",\"selected\":0,\"order\":56},{\"label\":\"Cuba\",\"value\":\"CU\",\"calc\":\"\",\"selected\":0,\"order\":57},{\"label\":\"Curacao\",\"value\":\"CW\",\"calc\":\"\",\"selected\":0,\"order\":58},{\"label\":\"Czechia\",\"value\":\"CZ\",\"calc\":\"\",\"selected\":0,\"order\":60},{\"label\":\"Dinamarca\",\"value\":\"DK\",\"calc\":\"\",\"selected\":0,\"order\":61},{\"label\":\"Dominica\",\"value\":\"DM\",\"calc\":\"\",\"selected\":0,\"order\":63},{\"label\":\"Ecuador\",\"value\":\"EC\",\"calc\":\"\",\"selected\":0,\"order\":66},{\"label\":\"Egipcia\",\"value\":\"EG\",\"calc\":\"\",\"selected\":0,\"order\":67},{\"label\":\"El Salvador\",\"value\":\"SV\",\"calc\":\"\",\"selected\":0,\"order\":68},{\"label\":\"Emiratos \\u00c1rabes Unidos \",\"value\":\"AE\",\"calc\":\"\",\"selected\":0,\"order\":238},{\"label\":\"England\",\"value\":\"EN\",\"calc\":\"\",\"selected\":0,\"order\":69},{\"label\":\"Eritrea\",\"value\":\"ER\",\"calc\":\"\",\"selected\":0,\"order\":71},{\"label\":\"Eslovenia \",\"value\":\"SI\",\"calc\":\"\",\"selected\":0,\"order\":208},{\"label\":\"Espa\\u00f1a\",\"value\":\"ES\",\"calc\":\"\",\"selected\":0,\"order\":214},{\"label\":\"Estados Federados de Micronesia \",\"value\":\"FM\",\"calc\":\"\",\"selected\":0,\"order\":148},{\"label\":\"Estados Unidos \",\"value\":\"US\",\"calc\":\"\",\"selected\":0,\"order\":240},{\"label\":\"Estonia\",\"value\":\"EE\",\"calc\":\"\",\"selected\":0,\"order\":72},{\"label\":\"Eswatini\",\"value\":\"SZ\",\"calc\":\"\",\"selected\":0,\"order\":73},{\"label\":\"Etiop\\u00eda \",\"value\":\"ET\",\"calc\":\"\",\"selected\":0,\"order\":74},{\"label\":\"Federaci\\u00f3n rusa\",\"value\":\"RU\",\"calc\":\"\",\"selected\":0,\"order\":188},{\"label\":\"Fiji\",\"value\":\"FJ\",\"calc\":\"\",\"selected\":0,\"order\":77},{\"label\":\"Filipinas \",\"value\":\"PH\",\"calc\":\"\",\"selected\":0,\"order\":180},{\"label\":\"Finlandia\",\"value\":\"FI\",\"calc\":\"\",\"selected\":0,\"order\":78},{\"label\":\"Francia\",\"value\":\"FR\",\"calc\":\"\",\"selected\":0,\"order\":79},{\"label\":\"Francia, Metropolitana \",\"value\":\"FX\",\"calc\":\"\",\"selected\":0,\"order\":80},{\"label\":\"Gab\\u00f3n \",\"value\":\"GA\",\"calc\":\"\",\"selected\":0,\"order\":84},{\"label\":\"Gambia\",\"value\":\"GM\",\"calc\":\"\",\"selected\":0,\"order\":85},{\"label\":\"Georgia\",\"value\":\"GE\",\"calc\":\"\",\"selected\":0,\"order\":86},{\"label\":\"Ghana\",\"value\":\"GH\",\"calc\":\"\",\"selected\":0,\"order\":88},{\"label\":\"Gibraltar\",\"value\":\"GI\",\"calc\":\"\",\"selected\":0,\"order\":89},{\"label\":\"Granada\",\"value\":\"GD\",\"calc\":\"\",\"selected\":0,\"order\":92},{\"label\":\"Grecia\",\"value\":\"GR\",\"calc\":\"\",\"selected\":0,\"order\":90},{\"label\":\"Groenlandia \",\"value\":\"GL\",\"calc\":\"\",\"selected\":0,\"order\":91},{\"label\":\"Guadalupe\",\"value\":\"GP\",\"calc\":\"\",\"selected\":0,\"order\":93},{\"label\":\"Guam\",\"value\":\"GU\",\"calc\":\"\",\"selected\":0,\"order\":94},{\"label\":\"Guatemala\",\"value\":\"GT\",\"calc\":\"\",\"selected\":0,\"order\":95},{\"label\":\"Guayana\",\"value\":\"GY\",\"calc\":\"\",\"selected\":0,\"order\":98},{\"label\":\"Guayana Francesa\",\"value\":\"GF\",\"calc\":\"\",\"selected\":0,\"order\":81},{\"label\":\"Guinea\",\"value\":\"GN\",\"calc\":\"\",\"selected\":0,\"order\":96},{\"label\":\"Guinea Ecuatorial\",\"value\":\"GQ\",\"calc\":\"\",\"selected\":0,\"order\":70},{\"label\":\"Guinea-Bissau \",\"value\":\"GW\",\"calc\":\"\",\"selected\":0,\"order\":97},{\"label\":\"Hait\\u00ed \",\"value\":\"HT\",\"calc\":\"\",\"selected\":0,\"order\":99},{\"label\":\"Honduras\",\"value\":\"HN\",\"calc\":\"\",\"selected\":0,\"order\":102},{\"label\":\"Hong Kong\",\"value\":\"HK\",\"calc\":\"\",\"selected\":0,\"order\":103},{\"label\":\"Hungr\\u00eda\",\"value\":\"HU\",\"calc\":\"\",\"selected\":0,\"order\":104},{\"label\":\"India\",\"value\":\"IN\",\"calc\":\"\",\"selected\":0,\"order\":106},{\"label\":\"Indonesia\",\"value\":\"ID\",\"calc\":\"\",\"selected\":0,\"order\":107},{\"label\":\"Irak\",\"value\":\"IQ\",\"calc\":\"\",\"selected\":0,\"order\":109},{\"label\":\"Irlanda\",\"value\":\"IE\",\"calc\":\"\",\"selected\":0,\"order\":110},{\"label\":\"Ir\\u00e1n (Rep\\u00fablica Isl\\u00e1mica de)\",\"value\":\"IR\",\"calc\":\"\",\"selected\":0,\"order\":108},{\"label\":\"Isla Bouvet \",\"value\":\"BV\",\"calc\":\"\",\"selected\":0,\"order\":31},{\"label\":\"Isla Norfolk \",\"value\":\"NF\",\"calc\":\"\",\"selected\":0,\"order\":168},{\"label\":\"Islandia \",\"value\":\"IS\",\"calc\":\"\",\"selected\":0,\"order\":105},{\"label\":\"Islas Caim\\u00e1n \",\"value\":\"KY\",\"calc\":\"\",\"selected\":0,\"order\":42},{\"label\":\"Islas Cocos ( Keeling) \",\"value\":\"CC\",\"calc\":\"\",\"selected\":0,\"order\":48},{\"label\":\"Islas Cook\",\"value\":\"CK\",\"calc\":\"\",\"selected\":0,\"order\":53},{\"label\":\"Islas Falkland (Malvinas)\",\"value\":\"FK\",\"calc\":\"\",\"selected\":0,\"order\":75},{\"label\":\"Islas Feroe \",\"value\":\"FO\",\"calc\":\"\",\"selected\":0,\"order\":76},{\"label\":\"Islas Heard y Mc Donald\",\"value\":\"HM\",\"calc\":\"\",\"selected\":0,\"order\":100},{\"label\":\"Islas Marianas del Norte\",\"value\":\"MP\",\"calc\":\"\",\"selected\":0,\"order\":170},{\"label\":\"Islas Marshall\",\"value\":\"MH\",\"calc\":\"\",\"selected\":0,\"order\":142},{\"label\":\"Islas Salom\\u00f3n\",\"value\":\"SB\",\"calc\":\"\",\"selected\":0,\"order\":209},{\"label\":\"Islas Svalbard y Jan Mayen\",\"value\":\"SJ\",\"calc\":\"\",\"selected\":0,\"order\":218},{\"label\":\"Islas Turcas y Caicos \",\"value\":\"TC\",\"calc\":\"\",\"selected\":0,\"order\":234},{\"label\":\"Islas V\\u00edrgenes ( EE.UU. )\",\"value\":\"VI\",\"calc\":\"\",\"selected\":0,\"order\":248},{\"label\":\"Islas V\\u00edrgenes (brit\\u00e1nicas)\",\"value\":\"VG\",\"calc\":\"\",\"selected\":0,\"order\":247},{\"label\":\"Isle of Man\",\"value\":\"IM\",\"calc\":\"\",\"selected\":0,\"order\":111},{\"label\":\"Israel\",\"value\":\"IL\",\"calc\":\"\",\"selected\":0,\"order\":112},{\"label\":\"Italia\",\"value\":\"IT\",\"calc\":\"\",\"selected\":0,\"order\":113},{\"label\":\"Jamaica\",\"value\":\"JM\",\"calc\":\"\",\"selected\":0,\"order\":114},{\"label\":\"Jap\\u00f3n \",\"value\":\"JP\",\"calc\":\"\",\"selected\":0,\"order\":115},{\"label\":\"Jersey\",\"value\":\"JE\",\"calc\":\"\",\"selected\":0,\"order\":116},{\"label\":\"Jordania\",\"value\":\"JO\",\"calc\":\"\",\"selected\":0,\"order\":117},{\"label\":\"Kazajst\\u00e1n \",\"value\":\"KZ\",\"calc\":\"\",\"selected\":0,\"order\":118},{\"label\":\"Kenia\",\"value\":\"KE\",\"calc\":\"\",\"selected\":0,\"order\":119},{\"label\":\"Kirguist\\u00e1n \",\"value\":\"KG\",\"calc\":\"\",\"selected\":0,\"order\":125},{\"label\":\"Kiribati\",\"value\":\"KI\",\"calc\":\"\",\"selected\":0,\"order\":120},{\"label\":\"Kuwait \",\"value\":\"KW\",\"calc\":\"\",\"selected\":0,\"order\":124},{\"label\":\"La Isla de Navidad\",\"value\":\"CX\",\"calc\":\"\",\"selected\":0,\"order\":47},{\"label\":\"La Rep\\u00fablica Democr\\u00e1tica del Congo \",\"value\":\"CD\",\"calc\":\"\",\"selected\":0,\"order\":52},{\"label\":\"Las Islas menores alejadas de los Estados Unidos \",\"value\":\"UM\",\"calc\":\"\",\"selected\":0,\"order\":241},{\"label\":\"Lesoto\",\"value\":\"LS\",\"calc\":\"\",\"selected\":0,\"order\":129},{\"label\":\"Letonia \",\"value\":\"LV\",\"calc\":\"\",\"selected\":0,\"order\":127},{\"label\":\"Liberia\",\"value\":\"LR\",\"calc\":\"\",\"selected\":0,\"order\":130},{\"label\":\"Libya\",\"value\":\"LY\",\"calc\":\"\",\"selected\":0,\"order\":131},{\"label\":\"Liechtenstein \",\"value\":\"LI\",\"calc\":\"\",\"selected\":0,\"order\":132},{\"label\":\"Lituania \",\"value\":\"LT\",\"calc\":\"\",\"selected\":0,\"order\":133},{\"label\":\"Luxemburgo \",\"value\":\"LU\",\"calc\":\"\",\"selected\":0,\"order\":134},{\"label\":\"L\\u00edbano \",\"value\":\"LB\",\"calc\":\"\",\"selected\":0,\"order\":128},{\"label\":\"Macao\",\"value\":\"MO\",\"calc\":\"\",\"selected\":0,\"order\":135},{\"label\":\"Madagascar\",\"value\":\"MG\",\"calc\":\"\",\"selected\":0,\"order\":136},{\"label\":\"Malawi\",\"value\":\"MW\",\"calc\":\"\",\"selected\":0,\"order\":137},{\"label\":\"Malaysia\",\"value\":\"MY\",\"calc\":\"\",\"selected\":0,\"order\":138},{\"label\":\"Maldivas\",\"value\":\"MV\",\"calc\":\"\",\"selected\":0,\"order\":139},{\"label\":\"Malta\",\"value\":\"MT\",\"calc\":\"\",\"selected\":0,\"order\":141},{\"label\":\"Mal\\u00ed \",\"value\":\"ML\",\"calc\":\"\",\"selected\":0,\"order\":140},{\"label\":\"Marruecos \",\"value\":\"MA\",\"calc\":\"\",\"selected\":0,\"order\":154},{\"label\":\"Martinica \",\"value\":\"MQ\",\"calc\":\"\",\"selected\":0,\"order\":143},{\"label\":\"Mauricio \",\"value\":\"MU\",\"calc\":\"\",\"selected\":0,\"order\":145},{\"label\":\"Mauritania \",\"value\":\"MR\",\"calc\":\"\",\"selected\":0,\"order\":144},{\"label\":\"Mayotte \",\"value\":\"YT\",\"calc\":\"\",\"selected\":0,\"order\":146},{\"label\":\"Mongolia\",\"value\":\"MN\",\"calc\":\"\",\"selected\":0,\"order\":151},{\"label\":\"Montenegro\",\"value\":\"ME\",\"calc\":\"\",\"selected\":0,\"order\":152},{\"label\":\"Montserrat  \",\"value\":\"MS\",\"calc\":\"\",\"selected\":0,\"order\":153},{\"label\":\"Mozambique \",\"value\":\"MZ\",\"calc\":\"\",\"selected\":0,\"order\":155},{\"label\":\"Myanmar \",\"value\":\"MM\",\"calc\":\"\",\"selected\":0,\"order\":156},{\"label\":\"M\\u00e9xico \",\"value\":\"MX\",\"calc\":\"\",\"selected\":0,\"order\":147},{\"label\":\"M\\u00f3naco \",\"value\":\"MC\",\"calc\":\"\",\"selected\":0,\"order\":150},{\"label\":\"Namibia\",\"value\":\"NA\",\"calc\":\"\",\"selected\":0,\"order\":157},{\"label\":\"Nauru\",\"value\":\"NR\",\"calc\":\"\",\"selected\":0,\"order\":158},{\"label\":\"Nepal \",\"value\":\"NP\",\"calc\":\"\",\"selected\":0,\"order\":159},{\"label\":\"Nicaragua\",\"value\":\"NI\",\"calc\":\"\",\"selected\":0,\"order\":164},{\"label\":\"Nigeria\",\"value\":\"NG\",\"calc\":\"\",\"selected\":0,\"order\":166},{\"label\":\"Niue\",\"value\":\"NU\",\"calc\":\"\",\"selected\":0,\"order\":167},{\"label\":\"North Macedonia\",\"value\":\"MK\",\"calc\":\"\",\"selected\":0,\"order\":169},{\"label\":\"Noruega\",\"value\":\"NO\",\"calc\":\"\",\"selected\":0,\"order\":171},{\"label\":\"Nueva Caledonia\",\"value\":\"NC\",\"calc\":\"\",\"selected\":0,\"order\":162},{\"label\":\"Nueva Zelanda\",\"value\":\"NZ\",\"calc\":\"\",\"selected\":0,\"order\":163},{\"label\":\"N\\u00edger \",\"value\":\"NE\",\"calc\":\"\",\"selected\":0,\"order\":165},{\"label\":\"Om\\u00e1n \",\"value\":\"OM\",\"calc\":\"\",\"selected\":0,\"order\":172},{\"label\":\"Pakist\\u00e1n \",\"value\":\"PK\",\"calc\":\"\",\"selected\":0,\"order\":173},{\"label\":\"Palau\",\"value\":\"PW\",\"calc\":\"\",\"selected\":0,\"order\":174},{\"label\":\"Palestine, State of\",\"value\":\"PS\",\"calc\":\"\",\"selected\":0,\"order\":175},{\"label\":\"Panama\",\"value\":\"PA\",\"calc\":\"\",\"selected\":0,\"order\":176},{\"label\":\"Pap\\u00faa Nueva Guinea \",\"value\":\"PG\",\"calc\":\"\",\"selected\":0,\"order\":177},{\"label\":\"Paraguay\",\"value\":\"PY\",\"calc\":\"\",\"selected\":0,\"order\":178},{\"label\":\"Pa\\u00edses Bajos\",\"value\":\"NL\",\"calc\":\"\",\"selected\":0,\"order\":160},{\"label\":\"Per\\u00fa \",\"value\":\"PE\",\"calc\":\"\",\"selected\":0,\"order\":179},{\"label\":\"Pitcairn \",\"value\":\"PN\",\"calc\":\"\",\"selected\":0,\"order\":181},{\"label\":\"Polinesia Francesa\",\"value\":\"PF\",\"calc\":\"\",\"selected\":0,\"order\":82},{\"label\":\"Polonia\",\"value\":\"PL\",\"calc\":\"\",\"selected\":0,\"order\":182},{\"label\":\"Portugal\",\"value\":\"PT\",\"calc\":\"\",\"selected\":0,\"order\":183},{\"label\":\"Puerto Rico\",\"value\":\"PR\",\"calc\":\"\",\"selected\":0,\"order\":184},{\"label\":\"Qatar\",\"value\":\"QA\",\"calc\":\"\",\"selected\":0,\"order\":185},{\"label\":\"Reino Unido \",\"value\":\"GB\",\"calc\":\"\",\"selected\":0,\"order\":239},{\"label\":\"Republic of Kosovo\",\"value\":\"RK\",\"calc\":\"\",\"selected\":0,\"order\":123},{\"label\":\"Rep\\u00fablica Centroafricana \",\"value\":\"CF\",\"calc\":\"\",\"selected\":0,\"order\":43},{\"label\":\"Rep\\u00fablica de Corea \",\"value\":\"KR\",\"calc\":\"\",\"selected\":0,\"order\":122},{\"label\":\"Rep\\u00fablica de Moldavia\",\"value\":\"MD\",\"calc\":\"\",\"selected\":0,\"order\":149},{\"label\":\"Rep\\u00fablica Democr\\u00e1tica Popular Lao\",\"value\":\"LA\",\"calc\":\"\",\"selected\":0,\"order\":126},{\"label\":\"Rep\\u00fablica Dominicana\",\"value\":\"DO\",\"calc\":\"\",\"selected\":0,\"order\":64},{\"label\":\"Rep\\u00fablica Popular Democr\\u00e1tica de Corea \",\"value\":\"KP\",\"calc\":\"\",\"selected\":0,\"order\":121},{\"label\":\"Rep\\u00fablica Unida de Tanzania\",\"value\":\"TZ\",\"calc\":\"\",\"selected\":0,\"order\":224},{\"label\":\"Rep\\u00fablica \\u00c1rabe Siria\",\"value\":\"SY\",\"calc\":\"\",\"selected\":0,\"order\":221},{\"label\":\"Reuni\\u00f3n\",\"value\":\"RE\",\"calc\":\"\",\"selected\":0,\"order\":186},{\"label\":\"Ruanda\",\"value\":\"RW\",\"calc\":\"\",\"selected\":0,\"order\":189},{\"label\":\"Ruman\\u00eda\",\"value\":\"RO\",\"calc\":\"\",\"selected\":0,\"order\":187},{\"label\":\"Saint  Martin\",\"value\":\"MF\",\"calc\":\"\",\"selected\":0,\"order\":194},{\"label\":\"Saint Barthelemy\",\"value\":\"BL\",\"calc\":\"\",\"selected\":0,\"order\":190},{\"label\":\"Saint Helena, Ascension and Tristan da Cunha\",\"value\":\"SH\",\"calc\":\"\",\"selected\":0,\"order\":191},{\"label\":\"Saint Pierre and Miquelon\",\"value\":\"PM\",\"calc\":\"\",\"selected\":0,\"order\":195},{\"label\":\"Samoa\",\"value\":\"WS\",\"calc\":\"\",\"selected\":0,\"order\":197},{\"label\":\"Samoa Americana \",\"value\":\"AS\",\"calc\":\"\",\"selected\":0,\"order\":5},{\"label\":\"San Crist\\u00f3bal y Nieves \",\"value\":\"KN\",\"calc\":\"\",\"selected\":0,\"order\":192},{\"label\":\"San Marino\",\"value\":\"SM\",\"calc\":\"\",\"selected\":0,\"order\":198},{\"label\":\"San Vicente y las Granadinas \",\"value\":\"VC\",\"calc\":\"\",\"selected\":0,\"order\":196},{\"label\":\"Santa Luc\\u00eda \",\"value\":\"LC\",\"calc\":\"\",\"selected\":0,\"order\":193},{\"label\":\"Santa Sede (Ciudad del Vaticano)\",\"value\":\"VA\",\"calc\":\"\",\"selected\":0,\"order\":101},{\"label\":\"Santo Tom\\u00e9 y Pr\\u00edncipe \",\"value\":\"ST\",\"calc\":\"\",\"selected\":0,\"order\":199},{\"label\":\"Senegal\",\"value\":\"SN\",\"calc\":\"\",\"selected\":0,\"order\":201},{\"label\":\"Serbia\",\"value\":\"RS\",\"calc\":\"\",\"selected\":0,\"order\":202},{\"label\":\"Seychelles \",\"value\":\"SC\",\"calc\":\"\",\"selected\":0,\"order\":203},{\"label\":\"Sierra Leona \",\"value\":\"SL\",\"calc\":\"\",\"selected\":0,\"order\":204},{\"label\":\"Singapur \",\"value\":\"SG\",\"calc\":\"\",\"selected\":0,\"order\":205},{\"label\":\"Sint Maarten\",\"value\":\"SX\",\"calc\":\"\",\"selected\":0,\"order\":206},{\"label\":\"Slovakia\",\"value\":\"SK\",\"calc\":\"\",\"selected\":0,\"order\":207},{\"label\":\"Somalia\",\"value\":\"SO\",\"calc\":\"\",\"selected\":0,\"order\":210},{\"label\":\"South Georgia and South Sandwich Islands\",\"value\":\"GS\",\"calc\":\"\",\"selected\":0,\"order\":212},{\"label\":\"South Sudan\",\"value\":\"SS\",\"calc\":\"\",\"selected\":0,\"order\":213},{\"label\":\"Sri Lanka\",\"value\":\"LK\",\"calc\":\"\",\"selected\":0,\"order\":215},{\"label\":\"Sud\\u00e1frica \",\"value\":\"ZA\",\"calc\":\"\",\"selected\":0,\"order\":211},{\"label\":\"Sud\\u00e1n \",\"value\":\"SD\",\"calc\":\"\",\"selected\":0,\"order\":216},{\"label\":\"Suecia\",\"value\":\"SE\",\"calc\":\"\",\"selected\":0,\"order\":219},{\"label\":\"Suiza\",\"value\":\"CH\",\"calc\":\"\",\"selected\":0,\"order\":220},{\"label\":\"Suriname\",\"value\":\"SR\",\"calc\":\"\",\"selected\":0,\"order\":217},{\"label\":\"S\\u00e1hara Occidental \",\"value\":\"EH\",\"calc\":\"\",\"selected\":0,\"order\":250},{\"label\":\"Tailandia \",\"value\":\"TH\",\"calc\":\"\",\"selected\":0,\"order\":225},{\"label\":\"Taiw\\u00e1n \",\"value\":\"TW\",\"calc\":\"\",\"selected\":0,\"order\":222},{\"label\":\"Tayikist\\u00e1n \",\"value\":\"TJ\",\"calc\":\"\",\"selected\":0,\"order\":223},{\"label\":\"Territorio Brit\\u00e1nico del Oc\\u00e9ano \\u00cdndico \",\"value\":\"IO\",\"calc\":\"\",\"selected\":0,\"order\":33},{\"label\":\"Territorios Franceses del Sur \",\"value\":\"TF\",\"calc\":\"\",\"selected\":0,\"order\":83},{\"label\":\"Timor-Leste\",\"value\":\"TL\",\"calc\":\"\",\"selected\":0,\"order\":226},{\"label\":\"Timor-Leste (Timor Oriental)\",\"value\":\"TL\",\"calc\":\"\",\"selected\":0,\"order\":65},{\"label\":\"Togo\",\"value\":\"TG\",\"calc\":\"\",\"selected\":0,\"order\":227},{\"label\":\"Tokelau \",\"value\":\"TK\",\"calc\":\"\",\"selected\":0,\"order\":228},{\"label\":\"Tonga\",\"value\":\"TO\",\"calc\":\"\",\"selected\":0,\"order\":229},{\"label\":\"Trinidad y Tobago \",\"value\":\"TT\",\"calc\":\"\",\"selected\":0,\"order\":230},{\"label\":\"Turkmenist\\u00e1n\",\"value\":\"TM\",\"calc\":\"\",\"selected\":0,\"order\":233},{\"label\":\"Turqu\\u00eda \",\"value\":\"TR\",\"calc\":\"\",\"selected\":0,\"order\":232},{\"label\":\"Tuvalu\",\"value\":\"TV\",\"calc\":\"\",\"selected\":0,\"order\":235},{\"label\":\"T\\u00fanez \",\"value\":\"TN\",\"calc\":\"\",\"selected\":0,\"order\":231},{\"label\":\"Ucrania \",\"value\":\"UA\",\"calc\":\"\",\"selected\":0,\"order\":237},{\"label\":\"Uganda\",\"value\":\"UG\",\"calc\":\"\",\"selected\":0,\"order\":236},{\"label\":\"Uruguay\",\"value\":\"UY\",\"calc\":\"\",\"selected\":0,\"order\":242},{\"label\":\"Uzbekist\\u00e1n \",\"value\":\"UZ\",\"calc\":\"\",\"selected\":0,\"order\":243},{\"label\":\"Vanuatu \",\"value\":\"VU\",\"calc\":\"\",\"selected\":0,\"order\":244},{\"label\":\"Venezuela\",\"value\":\"VE\",\"calc\":\"\",\"selected\":0,\"order\":245},{\"label\":\"Vietnam\",\"value\":\"VN\",\"calc\":\"\",\"selected\":0,\"order\":246},{\"label\":\"Wallis And Futuna\",\"value\":\"WF\",\"calc\":\"\",\"selected\":0,\"order\":249},{\"label\":\"Yemen \",\"value\":\"YE\",\"calc\":\"\",\"selected\":0,\"order\":251},{\"label\":\"Yibuti\",\"value\":\"DJ\",\"calc\":\"\",\"selected\":0,\"order\":62},{\"label\":\"Zambia\",\"value\":\"ZM\",\"calc\":\"\",\"selected\":0,\"order\":252},{\"label\":\"Zimbabue \",\"value\":\"ZW\",\"calc\":\"\",\"selected\":0,\"order\":253}],\"container_class\":\"\",\"element_class\":\"au-ninjaforms-element\",\"admin_label\":\"\",\"help_text\":\"\",\"default\":\"AR\",\"drawerDisabled\":false,\"value\":\"AR\",\"id\":63,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listcountry\",\"listselect\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":7,\"idAttribute\":\"id\",\"label\":\"C\\u00f3digo Postal\",\"type\":\"zip\",\"key\":\"codigo_postal_1539616201483\",\"label_pos\":\"above\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"au-ninjaforms-element\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caratteri rimasti\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"zip\",\"personally_identifiable\":\"\",\"value\":\"\",\"id\":64,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"zip\",\"element_templates\":[\"zip\",\"textbox\",\"input\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":8,\"idAttribute\":\"id\",\"label\":\"Mensaje\",\"type\":\"textarea\",\"key\":\"mensaje_1539617317414\",\"label_pos\":\"above\",\"required\":\"\",\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"au-ninjaforms-element\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caratteri rimasti\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"textarea_rte\":\"\",\"disable_rte_mobile\":\"\",\"textarea_media\":\"\",\"drawerDisabled\":false,\"value\":\"\",\"id\":66,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textarea\",\"element_templates\":[\"textarea\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":9,\"idAttribute\":\"id\",\"label\":\"Autorizo el tratamiento de los datos personales (Reg. 2016\\\/679\\\/UE).\",\"type\":\"checkbox\",\"key\":\"autorizo_el_tratamiento_de_los_datos_personales_reg_2016_679_ue_1551876833155\",\"label_pos\":\"right\",\"required\":1,\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"default_value\":\"unchecked\",\"checked_value\":\"Selezionato\",\"unchecked_value\":\"Deselezionato\",\"checked_calc_value\":\"\",\"unchecked_calc_value\":\"\",\"drawerDisabled\":false,\"id\":67,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":10,\"idAttribute\":\"id\",\"label\":\"Quiero recibir informaciones comerciales\",\"type\":\"checkbox\",\"key\":\"quiero_recibir_informaciones_comerciales_1539616254152\",\"label_pos\":\"right\",\"required\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"default_value\":\"unchecked\",\"checked_value\":\"Selezionato\",\"unchecked_value\":\"Deselezionato\",\"id\":68,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":11,\"idAttribute\":\"id\",\"label\":\"Enviar\",\"type\":\"submit\",\"processing_label\":\"Trattamento\",\"container_class\":\"\",\"element_class\":\"btn btn-outline-dark\",\"key\":\"enviar_1539616282718\",\"drawerDisabled\":false,\"id\":65,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"above\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n        ","protected":false},"excerpt":{"rendered":"El mundo entero est\u00e1 atravesando uno de los per\u00edodos m\u00e1s complicados de la era moderna, una pandemia que pone la estructura de nuestra sociedad en serias y profundas dificultades. Todos los sectores est\u00e1n experimentando cambios importantes, desde la atenci\u00f3n m\u00e9dica hasta las industrias, obviamente, hasta el turismo. Entre las pocas certezas que nos da el&#8230; <a class=\"view-article\" href=\"https:\/\/caesarluxurytravel.com\/es\/viajar-despues-del-coronavirus\/\">View Article<\/a>","protected":false},"author":3,"featured_media":1329,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[267,285,276,287,281,268,286,145],"class_list":["post-1336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuentos-de-italia","tag-consejos-de-viaje","tag-coronavirus-es","tag-coronavirus","tag-travel-designers-es","tag-travel-designers","tag-viaje-a-italia","tag-viaje-a-italia-en-2021","tag-viajes"],"_links":{"self":[{"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/posts\/1336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/comments?post=1336"}],"version-history":[{"count":2,"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/posts\/1336\/revisions"}],"predecessor-version":[{"id":1339,"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/posts\/1336\/revisions\/1339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/media\/1329"}],"wp:attachment":[{"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/media?parent=1336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/categories?post=1336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/caesarluxurytravel.com\/es\/wp-json\/wp\/v2\/tags?post=1336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}